{"id":1345,"date":"2022-06-05T12:07:42","date_gmt":"2022-06-05T10:07:42","guid":{"rendered":"https:\/\/taniagombert.com\/?p=1345"},"modified":"2026-03-29T12:06:46","modified_gmt":"2026-03-29T10:06:46","slug":"elementor-1345","status":"publish","type":"post","link":"https:\/\/taniagombert.com\/index.php\/2022\/06\/05\/elementor-1345\/","title":{"rendered":"L\u2019\u00e9cof\u00e9minisme, Femmes et Terre m\u00eame combat face au capitalisme"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"1345\" class=\"elementor elementor-1345\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-106dd0a9 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"106dd0a9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a0ac03d\" data-id=\"a0ac03d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2a1cf27a elementor-widget elementor-widget-theme-post-featured-image\" data-id=\"2a1cf27a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-featured-image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4311868d elementor-section-full_width elementor-section-height-min-height elementor-section-items-stretch elementor-reverse-tablet elementor-section-height-default\" data-id=\"4311868d\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3d058fbc\" data-id=\"3d058fbc\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-1aeeaf9f\" data-id=\"1aeeaf9f\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3eb7c6da elementor-widget elementor-widget-post-info\" data-id=\"3eb7c6da\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"post-info.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-316dcbb3 elementor-widget elementor-widget-theme-post-title\" data-id=\"316dcbb3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-37dfeb01 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"37dfeb01\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-370d7285\" data-id=\"370d7285\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-13beb3f elementor-widget elementor-widget-author-box\" data-id=\"13beb3f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"author-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-31fa2ad6\" data-id=\"31fa2ad6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7008868c elementor-widget elementor-widget-theme-post-excerpt\" data-id=\"7008868c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-excerpt.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-78e40fb elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"78e40fb\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-26e0de68\" data-id=\"26e0de68\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-44de2fad elementor-widget elementor-widget-heading\" data-id=\"44de2fad\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Share:<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-6c846607\" data-id=\"6c846607\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-13be5f36 elementor-widget elementor-widget-share-buttons\" data-id=\"13be5f36\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"share-buttons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ef43d61 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ef43d61\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b5dfe95\" data-id=\"b5dfe95\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-52bc6aa elementor-widget elementor-widget-text-editor\" data-id=\"52bc6aa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><a title=\"article ecofeminisme Tania Gombert\" href=\"https:\/\/www.linkedin.com\/pulse\/l%25C3%25A9cof%25C3%25A9minisme-redonner-leur-place-aux-femmes-et-%25C3%25A0-la-nature-gombert\/?trackingId=fyn%2FvofMSGOTy2LA70RJBA%3D%3D\" target=\"_blank\" rel=\"noopener\"><em>N\u00e9 des remises en question et de l\u2019analyse des causes de la <strong>domination masculine<\/strong> ainsi que du massacre de la plan\u00e8te, l\u2019\u00e9co-f\u00e9minisme bouscule \u00e0 la fois l\u2019\u00e9cologie et le f\u00e9minisme en tant que tels. Un mouvement qui se veut non clivant mais qui est encore trop souvent pluriel et divis\u00e9\u2026<\/em><\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2dc72b8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2dc72b8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b586c59\" data-id=\"b586c59\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ed36948 elementor-widget elementor-widget-text-editor\" data-id=\"ed36948\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Les travaux et r\u00e9flexions sur les liens entre genre et \u00e9cologie tr\u00e8s r\u00e9cents en France, sont le signe d\u2019une r\u00e9elle \u00e9volution aussi bien dans le domaine de l\u2019\u00e9cologie politique que de la <strong>pens\u00e9e f\u00e9ministe<\/strong>. Nous sommes en effet pass\u00e9s d\u2019un concept marginal et p\u00e9riph\u00e9rique \u00e0 une sensibilit\u00e9 \u00e9cof\u00e9ministe au c\u0153ur du combat qu\u2019est le f\u00e9minisme appel\u00e9 \u00ab\u00a0de troisi\u00e8me vague\u00a0\u00bb. Comme pour la mode, nous assistions \u00e0 un renouvellement des m\u0153urs au sein des mouvements \u00e9cologistes et <strong>f\u00e9ministes<\/strong> en eux-m\u00eames, faisant place \u00e0 une nouvelle g\u00e9n\u00e9ration de militants qui am\u00e8nent chacun leur propre interpr\u00e9tation du f\u00e9minisme. Je pense que nous devons nous r\u00e9jouir de cette pluralit\u00e9 et comprendre que c\u2019est de cette diversit\u00e9 que na\u00eet la force, la richesse et l\u2019inspiration d\u2019un tel mouvement.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6eb8a73 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6eb8a73\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-fee9b2f\" data-id=\"fee9b2f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8cd1afb elementor-widget elementor-widget-heading\" data-id=\"8cd1afb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/www.unwomen.org\/fr\/csw\" target=\"_blank\">Un contexte propice \u00e0 l\u2019\u00e9galit\u00e9 des sexes et l\u2019autonomisation des femmes : la Commission de la condition de la femme des Nations Unies (CSW)<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a776ca6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a776ca6\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c39151d\" data-id=\"c39151d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-10eb16c elementor-widget elementor-widget-text-editor\" data-id=\"10eb16c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><a title=\"Table ronde Tania Gombert ONU Femmes Ecof\u00e9minisme\" href=\"https:\/\/www.youtube.com\/watch?v=8Khc2vy_uVg&amp;t=6s\" target=\"_blank\" rel=\"noopener\">J\u2019ai \u00e9t\u00e9 chaleureusement convi\u00e9e \u00e0 participer \u00e0 la soixante-sixi\u00e8me \u00e9dition de la Commission de la condition de la femme pour intervenir, le 17 mars, \u00e0 une table ronde organis\u00e9e par l\u2019association <em>Femmes au-del\u00e0 des mers (FAM). <\/em>Le but du forum \u00e9tait de discuter\u00a0d\u2019in\u00e9galit\u00e9s de <strong>genres<\/strong>, d\u2019urgence climatique et de territorialit\u00e9 afin d\u2019apporter des solutions <strong>pour les femmes<\/strong> des Outre-mer.<\/a><\/p><p>Cette ann\u00e9e, la th\u00e9matique principale visait \u00e0 cr\u00e9er un d\u00e9bat ouvert sur le r\u00f4le des politiques d\u2019<strong>\u00e9galit\u00e9 des sexes<\/strong> dans le d\u00e9veloppement des carri\u00e8res universitaires et des environnements de travail, de mani\u00e8re \u00e0 encourager les changements de perspectives ainsi qu\u2019\u00e0 confirmer la n\u00e9cessit\u00e9 d\u2019une implication \u00e9quitable des femmes et des hommes dans les domaines de la science, de la recherche et de l\u2019innovation. Je me suis donc int\u00e9ress\u00e9e de plus pr\u00e8s \u00e0 cette cause qui faisait d\u00e9j\u00e0 \u00e9cho en moi.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-355eb41 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"355eb41\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9e0d537\" data-id=\"9e0d537\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9e58aac elementor-widget elementor-widget-heading\" data-id=\"9e58aac\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">F\u00e9minisme humaniste \/ universaliste vs \u00e9cof\u00e9minisme : un engagement profond, qui rallie et s\u00e9duit autant qu\u2019il inqui\u00e8te et divise<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-160aa0a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"160aa0a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f7bc6af\" data-id=\"f7bc6af\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-51ca540 elementor-widget elementor-widget-text-editor\" data-id=\"51ca540\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><a title=\"F\u00e9minisme Tania Gombert\" href=\"https:\/\/taniagombert.com\/index.php\/category\/feminisme-par-reaction\/\" target=\"_blank\" rel=\"noopener\">Je pr\u00f4ne un f\u00e9minisme universaliste car il ne peut, selon moi, y avoir de f\u00e9minisme sans humanisme.<\/a> Avant d\u2019\u00eatre des hommes ou des femmes, nous sommes des \u00eatres humains qui se veulent libres et \u00e9gaux en droits mais aussi en dignit\u00e9. Le clivage entre f\u00e9minisme universaliste et f\u00e9minisme intersectionnel \u2013 largement aliment\u00e9 par les m\u00e9dias \u2013 n\u2019a pas r\u00e9ellement de fondements, de la m\u00eame mani\u00e8re que le clivage entre celles qui se revendiquent <strong>f\u00e9ministes<\/strong> et les autres femmes ne devrait pas exister.<\/p><p>Comme je le dis toujours, je suis f\u00e9ministe par r\u00e9action et m\u2019insurge d\u2019entendre trop souvent mes cons\u0153urs clamer haut et fort de ne pas \u00eatre f\u00e9ministes alors qu\u2019elles sont pourtant elles aussi pour l\u2019\u00e9galit\u00e9 des <strong>sexes<\/strong> et qu\u2019elles s\u2019indignent des <strong>violences faites aux femmes<\/strong>. Les propos de Florence Montreynaud illustrent parfaitement mon positionnement\u00a0: \u00ab\u00a0On ne peut pas na\u00eetre f\u00e9ministe, puisqu\u2019on se donne cette identit\u00e9 au terme d\u2019un processus de conscientisation. Je me suis d\u00e9finie comme f\u00e9ministe en devenant adulte, par solidarit\u00e9 avec les femmes maltrait\u00e9es ou tortur\u00e9es en tant que femmes, et en prenant conscience de ma situation privil\u00e9gi\u00e9e.\u00a0\u00bb<\/p><p>Il en va de m\u00eame pour le <strong>f\u00e9minisme<\/strong> universaliste et l\u2019intersectionnel. Ce sont deux approches qui se rejoignent et se compl\u00e8tent au lieu de s\u2019affronter. Elles doivent toutes deux se baser sur la volont\u00e9 de faire converger les <strong>luttes<\/strong>, aussi multiples soient elles, sans en rel\u00e9guer une seule au second plan. Il faut d\u2019une part pouvoir se laisser guider par la notion d\u2019universalisme, comme un id\u00e9al \u00e0 atteindre et non pas le voir comme quelque chose d\u2019abstrait qui conduirait \u00e0 occulter des r\u00e9alit\u00e9s telles que le <strong>racisme<\/strong> ou les diverses <strong>discriminations<\/strong>. Puis d\u2019autre part, il faut arriver \u00e0 se servir de l\u2019<strong>intersectionnalit\u00e9<\/strong> comme d\u2019un outil d\u2019analyse tenant compte de la totalit\u00e9 des dynamiques de domination auxquelles nous pouvons \u00eatre confront\u00e9es, sans pour autant les hi\u00e9rarchiser.<\/p><p>Finalement, le lien naturel entre \u00ab\u00a0f\u00e9minisme\u00a0\u00bb et \u00ab\u00a0\u00e9cologie\u00a0\u00bb \u2013 deux victimes du <strong>capitalisme<\/strong> et du <strong>patriarcat<\/strong> \u2013 est des plus \u00e9vidents. L\u2019<strong>\u00e9cof\u00e9minisme<\/strong> est ainsi n\u00e9 afin de r\u00e9unir en un unique combat \u00ab\u00a0\u00e9cologie\u00a0\u00bb et \u00ab\u00a0f\u00e9minisme car les femmes et l\u2019environnement sont soumis \u00e0 un m\u00eame sc\u00e9nario de violence et de domination\u00a0: la destruction du premier contre l\u2019<strong>oppression<\/strong> de ces derni\u00e8res.<\/p><p>Pour un monde le plus \u00e9galitaire et durable possible, il est imp\u00e9ratif de lutter contre toutes les formes d\u2019oppressions, sans exception.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d167304 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d167304\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a0abc04\" data-id=\"a0abc04\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b0895d9 elementor-widget elementor-widget-heading\" data-id=\"b0895d9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Quand on parle d\u2019\u00e9cof\u00e9minisme, de quoi parle-t-on ?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8bf823c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8bf823c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-bba43f0\" data-id=\"bba43f0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c9e16be elementor-widget elementor-widget-text-editor\" data-id=\"c9e16be\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Depuis quelques mois, nous assistons en France \u00e0 l\u2019\u00e9mergence du terme \u00ab&nbsp;\u00e9cof\u00e9minisme&nbsp;\u00bb. Entre revendication du <strong>droit des femmes<\/strong> et pr\u00e9servation de la nature, il faut voir le f\u00e9minisme \u00e9cologique comme un courant des \u00e9thiques environnementales donnant une place centrale \u00e0 la question des relations de genre et de la <strong>domination<\/strong>, dans un cadre de protection environnementale. Les connexions existantes entre la domination des hommes sur la nature et sur les femmes sont donc au c\u0153ur des d\u00e9bats.<\/p>\n<p><\/p>\n<p>Il y a plusieurs raisons qui expliquent \u00e0 quel point faire le lien entre f\u00e9minisme et \u00e9cologie est aujourd\u2019hui in\u00e9vitable. En effet, ce sont g\u00e9n\u00e9ralement les m\u00eames peuples vuln\u00e9rables qui sont le plus directement impact\u00e9s par l\u2019exacerbation des in\u00e9galit\u00e9s dues aux changements climatiques. \u00c0 ce titre, les femmes qui repr\u00e9sentent \u00e0 elles seules, en 2021, 60 % de la population mondiale vivant sous le seuil de pauvret\u00e9, sont alors touch\u00e9es de mani\u00e8re extr\u00eame. D\u2019ailleurs, force est de constater que, pour la plupart des <strong>militantes<\/strong> se trouvant au Sud et sur qui le poids de la domination <strong>masculine<\/strong> p\u00e8se quotidiennement, la lutte \u00e9cologique est une question de survie.<\/p>\n<p>Voici l\u2019essence-m\u00eame de l\u2019\u00e9cof\u00e9minisme, qui est davantage un mouvement d\u2019actions que de pens\u00e9es, avec dans l\u2019id\u00e9e de combattre ensemble l\u2019exploitation de l\u2019environnement par les humains et l\u2019<strong>oppression des femmes<\/strong>. L\u2019\u00e9cof\u00e9minisme existe dans le but de repenser la soci\u00e9t\u00e9 de mani\u00e8re globale.<\/p>\n<p><\/p>\n<h2><br><\/h2>\n<p><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-427d281 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"427d281\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ad1cc64\" data-id=\"ad1cc64\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b1892cb elementor-widget elementor-widget-heading\" data-id=\"b1892cb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Histoire et grandes figures de l\u2019\u00e9cof\u00e9minisme<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e4d7be2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e4d7be2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-07ba38a\" data-id=\"07ba38a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c8b459e elementor-widget elementor-widget-text-editor\" data-id=\"c8b459e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Bien que ces derni\u00e8res ann\u00e9es semblent l\u2019avoir remis au go\u00fbt du jour, de nombreuses figures <strong>f\u00e9minines<\/strong>, qu\u2019elles soient \u00e9crivaines, chercheuses ou encore militantes, se sont investies depuis des d\u00e9cennies dans l\u2019\u00e9cof\u00e9minisme, qui pourrait \u00eatre d\u00e9fini comme un mouvement interdisciplinaire.<\/p><p>\u00a0<\/p><p>Le mot \u00ab\u00a0\u00e9cof\u00e9minisme\u00a0\u00bb est apparu pour la premi\u00e8re fois dans un livre de la <strong>militante<\/strong> et \u00e9crivaine fran\u00e7aise Fran\u00e7oise d\u2019Eaubonne, intitul\u00e9 <em>Le F\u00e9minisme ou la mort, <\/em>en 1974<em>. <\/em>Cette derni\u00e8re fonda le <strong>MLF<\/strong> (le <strong>Mouvement de Lib\u00e9ration des Femmes<\/strong>) en 1970 puis l\u2019association <em>\u00c9cologie F\u00e9minisme Centre<\/em> en 1974.<\/p><p>\u00a0<\/p><p>N\u00e9anmoins, l\u2019origine du mouvement pourrait remonter \u00e0 plus loin encore, jusqu\u2019en 1962 au moins, date de publication de <em>Silent Spring<\/em>, de Rachel Carson, une biologiste \u00e9m\u00e9rite am\u00e9ricaine. Cet ouvrage fut l\u2019une des premi\u00e8res publications \u00e0 d\u00e9noncer les pollutions aux pesticides et \u00e0 pr\u00e9senter une remise en question de l\u2019approche techniciste des probl\u00e9matiques environnementales. Ce dernier eut des r\u00e9percussions consid\u00e9rables. En tant que pr\u00e9curseur embl\u00e9matique de l\u2019\u00e9cof\u00e9minisme, Rachel Carson re\u00e7ut plusieurs r\u00e9compenses au cours de sa carri\u00e8re dont un <em>U.S National Book Award<\/em> ainsi que la m\u00e9daille pr\u00e9sidentielle de la Libert\u00e9, \u00e0 titre posthume.<\/p><p>\u00a0<\/p><p>Nous avons ensuite eu Maria Mies, une <strong>sociologue<\/strong> allemande repr\u00e9sentant quant \u00e0 elle le mouvement \u00e9cof\u00e9ministe dit socio\u00e9conomique\u00a0; Carolyne Merchant, une philosophe et historienne des sciences am\u00e9ricaine qui reprochait au si\u00e8cle des Lumi\u00e8res d\u2019\u00eatre le point de d\u00e9part de la domination de l\u2019homme sur la Nature et la femme\u00a0; Wangari Muta Maathi qui, forte de son titre de biologiste et professeure en m\u00e9decine v\u00e9t\u00e9rinaire au Kenya, a consacr\u00e9 sa vie \u00e0 la lutte environnementale ainsi qu\u2019\u00e0 la d\u00e9fense de la d\u00e9mocratie et de la paix\u00a0; Ariel Salleh, sociologue et militante \u00e9cof\u00e9ministe australienne\u00a0; Karen J. Warren, une pilosophe am\u00e9ricaine\u00a0; Starhawk, une journaliste et militante am\u00e9ricaine ou encore Vandana Shiva, philosophe et \u00e9cologiste militante indienne, donnant une voix \u00e0 l\u2019\u00e9cof\u00e9ministe dans les pays du Sud et enfin \u00c9milie Hache, une philosophe fran\u00e7aise encore tr\u00e8s investie aujourd\u2019hui. \u00a0\u00c0 l\u2019heure actuelle, c\u2019est l\u2019\u00e9cologiste Sandrine Rousseau qui rev\u00eat, \u00e0 son tour, les couleurs de l\u2019alliance de ces deux luttes. Une notion in\u00e9dite sur la sc\u00e8ne politique\u2026<\/p><p>\u00a0<\/p><p>L\u2019\u00e9cof\u00e9minisme n\u2019est pas une mode mais un flambeau que les femmes \u00e0 travers le monde se passent de g\u00e9n\u00e9ration en g\u00e9n\u00e9ration.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7ea1371 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7ea1371\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d652c2c\" data-id=\"d652c2c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-06d6550 elementor-widget elementor-widget-heading\" data-id=\"06d6550\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">La nouvelle g\u00e9n\u00e9ration de l\u2019\u00e9cof\u00e9minisme<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-23351ce elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"23351ce\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2c2c0a1\" data-id=\"2c2c0a1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-94e47cd elementor-widget elementor-widget-text-editor\" data-id=\"94e47cd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u00ab\u00a0Les jeunes ne resteront pas silencieux\u00a0\u00bb, c\u2019est ce que Maria Christina Kolo affirme lorsque l\u2019on parle de climat et de f\u00e9minisme. Militante climatique, \u00e9cof\u00e9ministe et entrepreneure sociale, cette jeune femme originaire de Madagascar nous explique tr\u00e8s simplement l\u2019analogie faite entre la soumission des femmes et de la Nature sous le poids de l\u2019homme\u00a0: \u00ab\u00a0On se permet de s\u2019accaparer la Terre comme on s\u2019accapare le corps de la femme sans que la nature ou que la femme ait son mot \u00e0 dire\u00a0\u00bb. Ce constat, qui me semble juste et r\u00e9voltant, donne tout son sens au concept d\u2019\u00e9cof\u00e9minisme.<\/p><p><br \/>En tant que jeune femme malgache engag\u00e9e, elle est elle-m\u00eame victime de nombreuses attaques et <strong>insultes<\/strong>, ce qui ne l\u2019emp\u00eache pas pour autant d\u2019incarner depuis toute petite, l\u2019insoumission et l\u2019<strong>engagement<\/strong> dans sa vie quotidienne. Ses actions et sa voix d\u00e9rangent mais Marie Christina Kolo a su en faire une force.<\/p><p>\u00a0<\/p><p>Apr\u00e8s avoir cr\u00e9\u00e9 son entreprise sociale en 2016, GreenNKool s\u2019engage depuis plus de 5 ans dans la gestion des d\u00e9chets communautaires, la cr\u00e9ation d\u2019activit\u00e9s lucratives autour du recyclage et d\u2019emplois verts pour les plus d\u00e9munis. Elle n\u2019h\u00e9site pas non plus \u00e0 prendre la parole pour d\u00e9noncer les <strong>viols<\/strong> ou \u00e0 montrer les coupables du doigt et a m\u00eame cr\u00e9\u00e9 une plateforme digitale pour venir en aide aux victimes.<\/p><p>\u00a0<\/p><p>Puis sur un axe plus familier, nous avons ma ni\u00e8ce, une jeune femme m\u00e9tisse (Martinique \/ Madagascar) qui repr\u00e9sente aussi tr\u00e8s bien le futur visage de l\u2019\u00e9cof\u00e9minisme. Ambitieuse et dot\u00e9 d\u2019un fort caract\u00e8re, elle a d\u00e9cid\u00e9 de faire ses \u00e9tudes en France et a int\u00e9gr\u00e9 un Master en risques naturels et environnement. Du haut de son jeune \u00e2ge, elle a tr\u00e8s rapidement su cerner ce qui ne tournait pas rond dans notre soci\u00e9t\u00e9 et notre monde. Particuli\u00e8rement sensible et r\u00e9volt\u00e9e, celle qui pour qui l\u2019<strong>\u00e9galit\u00e9<\/strong> n\u2019est d\u00e9j\u00e0 plus une question \u00e0 se poser ne baissera jamais les bras face aux urgences climatiques auxquelles nous sommes confront\u00e9s.<\/p><p>\u00a0<\/p><p>Plus qu\u2019une vocation, ma ni\u00e8ce n\u2019a pas eu le choix que de suivre son instinct et ses tripes qui lui indiquaient depuis son plus jeune \u00e2ge le chemin qu\u2019elle devait emprunter. Contribuer \u00e0 pr\u00e9server Dame Nature et la beaut\u00e9 de son \u00eele, intervenir pour r\u00e9veiller les consciences ainsi que montrer l\u2019exemple et ouvrir la voie. C\u2019est avec cette nouvelle jeune g\u00e9n\u00e9ration sensible, que nous construisons un futur fait de grandes aspirations.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5e50a837 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5e50a837\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a548881\" data-id=\"a548881\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3361bc16 elementor-widget elementor-widget-post-comments\" data-id=\"3361bc16\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"post-comments.theme_comments\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a3e3eac elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a3e3eac\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-36b109a0\" data-id=\"36b109a0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3833e525 elementor-widget-divider--view-line_text elementor-widget-divider--element-align-right elementor-widget elementor-widget-divider\" data-id=\"3833e525\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t\t<span class=\"elementor-divider__text elementor-divider__element\">\n\t\t\t\tOn Key\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-122389ce elementor-widget elementor-widget-heading\" data-id=\"122389ce\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Related Posts<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-382c3bfc elementor-widget elementor-widget-posts\" data-id=\"382c3bfc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"posts.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-588b80fb elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"588b80fb\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1936775f\" data-id=\"1936775f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6c18fd3c elementor-widget elementor-widget-post-navigation\" data-id=\"6c18fd3c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"post-navigation.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Share: Facebook Twitter Pinterest LinkedIn N\u00e9 des remises en question et de l\u2019analyse des causes de la domination masculine ainsi que du massacre de la plan\u00e8te, l\u2019\u00e9co-f\u00e9minisme bouscule \u00e0 la fois l\u2019\u00e9cologie et le f\u00e9minisme en tant que tels. Un mouvement qui se veut non clivant mais qui est encore trop souvent pluriel et divis\u00e9\u2026[&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"zakra_general_container_width":0,"zakra_general_content_width":0,"zakra_general_sidebar_width":0,"zakra_sticky_header":"customizer","zakra_header_main_area":true,"zakra_site_logo_width":0,"zakra_header_top_enabled":"customizer","zakra_header_top_style":"customizer","zakra_primary_menu_item_style":"customizer","zakra_page_header_text_color":"","zakra_page_header_layout":"customizer","zakra_page_title_bg":"","zakra_footer_widgets_bg_image":0,"zakra_page_title_bg_repeat":"customizer","zakra_page_title_bg_position":"customizer","zakra_page_title_bg_size":"customizer","zakra_page_title_bg_attachment":"customizer","zakra_breadcrumbs_enabled":"customizer","zakra_breadcrumbs_text_color":"","zakra_breadcrumbs_separator_color":"","zakra_breadcrumbs_link_color":"","zakra_breadcrumbs_link_hover_color":"","zakra_page_title_bg_image":0,"zakra_footer_widgets_enabled":"customizer","zakra_footer_column_layout_1_style":"customizer","zakra_footer_widgets_bg":"","zakra_footer_widgets_bg_repeat":"customizer","zakra_footer_widgets_bg_position":"customizer","zakra_footer_widgets_bg_size":"customizer","zakra_footer_widgets_bg_attachment":"customizer","zakra_footer_bar_enabled":"customizer","zakra_footer_bar_style":"customizer","zakra_page_container_layout":"customizer","zakra_page_sidebar_layout":"customizer","zakra_remove_content_margin":false,"zakra_sidebar":"customizer","zakra_transparent_header":"customizer","zakra_logo":0,"zakra_main_header_style":"default","zakra_menu_item_color":"","zakra_menu_item_hover_color":null,"zakra_menu_item_active_color":"","zakra_menu_active_style":"","zakra_page_header":true,"om_disable_all_campaigns":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[7],"tags":[19],"class_list":["post-1345","post","type-post","status-publish","format-standard","hentry","category-feminisme","tag-feminisme-ecofeminisme-environnement-domination-engagement-capitalsme"],"_links":{"self":[{"href":"https:\/\/taniagombert.com\/index.php\/wp-json\/wp\/v2\/posts\/1345","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/taniagombert.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/taniagombert.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/taniagombert.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/taniagombert.com\/index.php\/wp-json\/wp\/v2\/comments?post=1345"}],"version-history":[{"count":35,"href":"https:\/\/taniagombert.com\/index.php\/wp-json\/wp\/v2\/posts\/1345\/revisions"}],"predecessor-version":[{"id":1581,"href":"https:\/\/taniagombert.com\/index.php\/wp-json\/wp\/v2\/posts\/1345\/revisions\/1581"}],"wp:attachment":[{"href":"https:\/\/taniagombert.com\/index.php\/wp-json\/wp\/v2\/media?parent=1345"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/taniagombert.com\/index.php\/wp-json\/wp\/v2\/categories?post=1345"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/taniagombert.com\/index.php\/wp-json\/wp\/v2\/tags?post=1345"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}